{"id":3779,"count":1,"description":"","link":"https:\/\/cetechbpa.com\/gh\/product-category\/home-garden\/decor\/wind-wheels-spinners\/","name":"Wind Wheels &amp; Spinners","slug":"wind-wheels-spinners","taxonomy":"product_cat","parent":2011,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wind Wheels &amp; Spinners Archives - CETECH Ghana Departmental Hardware Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cetechbpa.com\/gh\/product-category\/home-garden\/decor\/wind-wheels-spinners\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wind Wheels &amp; Spinners Archives - CETECH Ghana Departmental Hardware Store\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cetechbpa.com\/gh\/product-category\/home-garden\/decor\/wind-wheels-spinners\/\" \/>\n<meta property=\"og:site_name\" content=\"CETECH Ghana Departmental Hardware Store\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/cetechbpa.com\\\/gh\\\/product-category\\\/home-garden\\\/decor\\\/wind-wheels-spinners\\\/\",\"url\":\"https:\\\/\\\/cetechbpa.com\\\/gh\\\/product-category\\\/home-garden\\\/decor\\\/wind-wheels-spinners\\\/\",\"name\":\"Wind Wheels &amp; Spinners Archives - CETECH Ghana Departmental Hardware Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cetechbpa.com\\\/gh\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cetechbpa.com\\\/gh\\\/product-category\\\/home-garden\\\/decor\\\/wind-wheels-spinners\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cetechbpa.com\\\/gh\\\/product-category\\\/home-garden\\\/decor\\\/wind-wheels-spinners\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cetechbpa.com\\\/gh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home &amp; Garden\",\"item\":\"https:\\\/\\\/cetechbpa.com\\\/gh\\\/product-category\\\/home-garden\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Decor\",\"item\":\"https:\\\/\\\/cetechbpa.com\\\/gh\\\/product-category\\\/home-garden\\\/decor\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Wind Wheels &amp; Spinners\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cetechbpa.com\\\/gh\\\/#website\",\"url\":\"https:\\\/\\\/cetechbpa.com\\\/gh\\\/\",\"name\":\"CETECH Ghana Departmental Hardware Store\",\"description\":\"Be Pleasantly Amazed \u2013 cetechbpa.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cetechbpa.com\\\/gh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wind Wheels &amp; Spinners Archives - CETECH Ghana Departmental Hardware Store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cetechbpa.com\/gh\/product-category\/home-garden\/decor\/wind-wheels-spinners\/","og_locale":"en_US","og_type":"article","og_title":"Wind Wheels &amp; Spinners Archives - CETECH Ghana Departmental Hardware Store","og_url":"https:\/\/cetechbpa.com\/gh\/product-category\/home-garden\/decor\/wind-wheels-spinners\/","og_site_name":"CETECH Ghana Departmental Hardware Store","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cetechbpa.com\/gh\/product-category\/home-garden\/decor\/wind-wheels-spinners\/","url":"https:\/\/cetechbpa.com\/gh\/product-category\/home-garden\/decor\/wind-wheels-spinners\/","name":"Wind Wheels &amp; Spinners Archives - CETECH Ghana Departmental Hardware Store","isPartOf":{"@id":"https:\/\/cetechbpa.com\/gh\/#website"},"breadcrumb":{"@id":"https:\/\/cetechbpa.com\/gh\/product-category\/home-garden\/decor\/wind-wheels-spinners\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/cetechbpa.com\/gh\/product-category\/home-garden\/decor\/wind-wheels-spinners\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cetechbpa.com\/gh\/"},{"@type":"ListItem","position":2,"name":"Home &amp; Garden","item":"https:\/\/cetechbpa.com\/gh\/product-category\/home-garden\/"},{"@type":"ListItem","position":3,"name":"Decor","item":"https:\/\/cetechbpa.com\/gh\/product-category\/home-garden\/decor\/"},{"@type":"ListItem","position":4,"name":"Wind Wheels &amp; Spinners"}]},{"@type":"WebSite","@id":"https:\/\/cetechbpa.com\/gh\/#website","url":"https:\/\/cetechbpa.com\/gh\/","name":"CETECH Ghana Departmental Hardware Store","description":"Be Pleasantly Amazed \u2013 cetechbpa.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cetechbpa.com\/gh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/cetechbpa.com\/gh\/wp-json\/wp\/v2\/product_cat\/3779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cetechbpa.com\/gh\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/cetechbpa.com\/gh\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/cetechbpa.com\/gh\/wp-json\/wp\/v2\/product_cat\/2011"}],"wp:post_type":[{"href":"https:\/\/cetechbpa.com\/gh\/wp-json\/wp\/v2\/product?product_cat=3779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}